{"id":23931,"date":"2024-02-05T17:16:12","date_gmt":"2024-02-05T16:16:12","guid":{"rendered":"https:\/\/map-dev.ch\/cossbouge\/?post_type=cpt_services&#038;p=23931"},"modified":"2024-02-07T16:48:13","modified_gmt":"2024-02-07T15:48:13","slug":"_-a-dupliquer-pour-creer-un-nouveau-membre-cloned-23481-2","status":"publish","type":"cpt_services","link":"https:\/\/map-dev.ch\/cossbouge\/membres\/_-a-dupliquer-pour-creer-un-nouveau-membre-cloned-23481-2\/","title":{"rendered":"Boucherie de la Venoge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"23931\" class=\"elementor elementor-23931\" data-elementor-post-type=\"cpt_services\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8aea4f4 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"8aea4f4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d423bd sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"6d423bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4422794 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4422794\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa8779a sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"fa8779a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Boucherie de la Venoge<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c958446 size-around sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c958446\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c72c4 elementor-view-default sc_fly_static elementor-widget elementor-widget-icon\" data-id=\"50c72c4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-sink\" href=\"#content_skip_link_anchor\">\n\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-797b5e3 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"797b5e3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cd0b2c elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"7cd0b2c\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-737ab48 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"737ab48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f23173 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"9f23173\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Boucherie de la Venoge<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2db405 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"c2db405\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>C&#8217;est le\u00a0<strong>14 f\u00e9vrier 1983<\/strong>\u00a0que commence cette belle aventure avec l&#8217;ouverture de la \u201d<strong>Boucherie de la Place<\/strong>\u201d\u00a0\u00e0 Cossonay-Ville\u00a0<em>(reprise d\u2019une ancienne boucherie ferm\u00e9e depuis 1 an)<\/em>\u00a0par Jean-Pierre Rochat et sa famille.<\/p><p>L&#8217;ann\u00e9e s&#8217;\u00e9coule, un employ\u00e9 et deux auxiliaires rejoignent notre \u00e9quipe.<\/p><p>La Boucherie de la Place devient &#8220;<strong>La Boucherie de la Venoge<\/strong>&#8220;.<\/p><p>De\u00a0<strong>1999\u00a0<\/strong>\u00e0\u00a0<strong>2002<\/strong>, son fils S\u00e9bastien\u00a0entreprend son apprentissage de boucher.<br \/>C&#8217;est en\u00a0<strong>2005<\/strong>\u00a0qu&#8217;il int\u00e8gre la boucherie familiale.\u00a0 Au vu de la passion et de la motivation qu&#8217;il d\u00e9gage pour son m\u00e9tier, nous prenons la de\u0301cision d\u2019agrandir et c\u2019est donc en\u00a0<strong>2006<\/strong>, a\u0300 Pa\u0302ques, que la Boucherie s\u2019installe a\u0300 la Rte de Morges 23 avec cinq employe\u0301s.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a805b5 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"7a805b5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"435\" src=\"https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/Rochat.jpg\" class=\"attachment-large size-large wp-image-23944\" alt=\"\" srcset=\"https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/Rochat.jpg 650w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/Rochat-300x201.jpg 300w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/Rochat-370x248.jpg 370w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/Rochat-410x274.jpg 410w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/Rochat-600x402.jpg 600w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d481214 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d481214\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-393aa97 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"393aa97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1eb9027 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"1eb9027\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a1559e2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a1559e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4cc77c sc_fly_static elementor-widget elementor-widget-image\" data-id=\"f4cc77c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"571\" src=\"https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto.jpg\" class=\"attachment-large size-large wp-image-23948\" alt=\"\" srcset=\"https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto.jpg 1000w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto-300x171.jpg 300w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto-768x439.jpg 768w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto-370x211.jpg 370w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto-840x480.jpg 840w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto-410x234.jpg 410w, https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/showPhoto-600x343.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b986308 elementor-align-center sc_fly_static elementor-widget elementor-widget-button\" data-id=\"b986308\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/boucheriedelavenoge.com\/index.php\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Site internet<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0de8b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e0de8b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1bb10e3 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1bb10e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d9fbb8 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"3d9fbb8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Contact<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab37191 elementor-widget-divider--view-line sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"ab37191\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bf90c1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width sc_fly_static elementor-widget elementor-widget-icon-list\" data-id=\"9bf90c1\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Route de Morges 23 1304 Cossonay-Ville<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@boucheriedelavenoge.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">021 861 04 49<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1170d0d elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"1170d0d\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e1a897 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"2e1a897\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66590c3 sc_fly_static elementor-widget elementor-widget-template\" data-id=\"66590c3\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"23475\" class=\"elementor elementor-23475\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22d237c elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"22d237c\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f50d65 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1f50d65\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57b450d sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"57b450d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Autres membres<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76181c7 sc_fly_static elementor-widget elementor-widget-trx_sc_services\" data-id=\"76181c7\" data-element_type=\"widget\" data-widget_type=\"trx_sc_services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sc_services sc_services_classic sc_services_featured_top\"><div class=\"sc_services_columns_wrap sc_item_columns sc_item_posts_container sc_item_columns_3 trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\"><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"23683\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-23683 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-boulangerie-patisserie\">\r\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/clement.jpg);\">\r\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\r\n                    <div class=\"sc_services_item_title_wrap\">\r\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/p-clement-boulangerie-patisserie-confisserie\/\">P. Cl\u00e9ment Boulangerie P\u00e2tisserie Confisserie<\/a><\/h6>\r\n                        <div class=\"sc_services_item_subtitle\"><a href=\"https:\/\/map-dev.ch\/cossbouge\/services_group\/boulangerie-patisserie\/\" title=\"View all posts in Boulangerie\/P\u00e2tisserie\">Boulangerie\/P\u00e2tisserie<\/a><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\r\n                        <a href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/p-clement-boulangerie-patisserie-confisserie\/\" class=\"sc_services_item_more_link\">\r\n                            <span class=\"link_text\">Voir le membre<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a>\r\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/p-clement-boulangerie-patisserie-confisserie\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"24387\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-24387 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-batiment\">\r\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/2_2516_fr.jpg);\">\r\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\r\n                    <div class=\"sc_services_item_title_wrap\">\r\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/menuiserie-michel-peter\/\">Menuiserie Michel P\u00e9ter<\/a><\/h6>\r\n                        <div class=\"sc_services_item_subtitle\"><a href=\"https:\/\/map-dev.ch\/cossbouge\/services_group\/batiment\/\" title=\"View all posts in B\u00e2timent\">B\u00e2timent<\/a><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\r\n                        <a href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/menuiserie-michel-peter\/\" class=\"sc_services_item_more_link\">\r\n                            <span class=\"link_text\">Voir le membre<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a>\r\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/menuiserie-michel-peter\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"24354\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-24354 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-restauration-alimentation\">\r\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/map-dev.ch\/cossbouge\/wp-content\/uploads\/2024\/02\/telecharger-14.jpg);\">\r\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\r\n                    <div class=\"sc_services_item_title_wrap\">\r\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/kebab-pizza\/\">Kebab Pizza<\/a><\/h6>\r\n                        <div class=\"sc_services_item_subtitle\"><a href=\"https:\/\/map-dev.ch\/cossbouge\/services_group\/restauration-alimentation\/\" title=\"View all posts in Restaurant\">Restaurant<\/a><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\r\n                        <a href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/kebab-pizza\/\" class=\"sc_services_item_more_link\">\r\n                            <span class=\"link_text\">Voir le membre<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a>\r\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/map-dev.ch\/cossbouge\/membres\/kebab-pizza\/\"><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Boucherie de la Venoge Boucherie de la Venoge C&#8217;est le\u00a014 f\u00e9vrier 1983\u00a0que commence cette belle aventure avec l&#8217;ouverture de la \u201dBoucherie de la Place\u201d\u00a0\u00e0 Cossonay-Ville\u00a0(reprise d\u2019une ancienne boucherie ferm\u00e9e depuis&hellip;<\/p>\n","protected":false},"author":6,"featured_media":24252,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","cpt_services_group":[238],"class_list":["post-23931","cpt_services","type-cpt_services","status-publish","has-post-thumbnail","hentry","cpt_services_group-boucherie-charcuterie"],"_links":{"self":[{"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/cpt_services\/23931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/cpt_services"}],"about":[{"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/types\/cpt_services"}],"author":[{"embeddable":true,"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/comments?post=23931"}],"version-history":[{"count":30,"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/cpt_services\/23931\/revisions"}],"predecessor-version":[{"id":24255,"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/cpt_services\/23931\/revisions\/24255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/media\/24252"}],"wp:attachment":[{"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/media?parent=23931"}],"wp:term":[{"taxonomy":"cpt_services_group","embeddable":true,"href":"https:\/\/map-dev.ch\/cossbouge\/wp-json\/wp\/v2\/cpt_services_group?post=23931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}